{"id":2071,"date":"2016-11-20T18:25:13","date_gmt":"2016-11-20T17:25:13","guid":{"rendered":"http:\/\/amicsnepal.blog.pangea.org\/?p=2071"},"modified":"2016-12-06T02:55:39","modified_gmt":"2016-12-06T01:55:39","slug":"bye-bye-to-the-rana-building-that-housed-the-public-school-of-bhimphedi-built-in-1933","status":"publish","type":"post","link":"https:\/\/amicsnepal.blog.pangea.org\/es\/2016\/11\/20\/bye-bye-to-the-rana-building-that-housed-the-public-school-of-bhimphedi-built-in-1933\/","title":{"rendered":"Adi\u00f3s al edificio Rana que ha alojado la escuela p\u00fablica de Bhimphedi, constru\u00efdo en 1933"},"content":{"rendered":"<p><\/p>\n<div>\n<p><strong>Escrito por M\u00f2nica Sans, co-responsable de la casa de acogida de Bhimphedi y co-coordinadora de AWASUKA<\/strong><\/p>\n<p>La dinast\u00eda Rana gobern\u00f3 Nepal desde 1846 hasta 1951, reduciendo a la monarqu\u00eda a una mera figura y haciendo que los cargos de Primer Ministro fueran hereditarios. El gobierno Rana se caracteriz\u00f3 por ser una tiran\u00eda con excesos, explotaci\u00f3n econ\u00f3mica y persecuciones religiosas. Sin embargo, los Rana desarrollaron muchas infraestructuras en el pa\u00eds y Bhimphedi es un buen ejemplo de ello: el hospital (era el segundo del pa\u00eds en la \u00e9poca), el edificio de la escuela p\u00fablica, Hatisar la casa de los elefantes (donde se guardan a\u00fan sillas de montar de \u00e9poca), el palacio de los ministros rana (actualmente en la c\u00e1rcel), <a href=\"http:\/\/amicsnepal.blog.pangea.org\/2015\/10\/19\/renovating-a-rana-palace\/\" target=\"_blank\">el palacio real<\/a> (actualmente dentro del recinto del orfanato de Balmandir), el edificio Janajati Hall (actualmente hotel de entidades, antiguamente residencia temporal del primer ministro ingl\u00e9s) y muchos edificios m\u00e1s. Y adem\u00e1s de los edificios, tambi\u00e9n construyeron la red de agua y los dep\u00f3sitos que a\u00fan hoy en d\u00eda abastecen el pueblo.<\/p>\n<figure id=\"attachment_2150-3\" aria-describedby=\"caption-attachment-2150-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010678.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2150 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010678.jpg\" alt=\"p1010678\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010678.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010678-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2150-3\" class=\"wp-caption-text\">Uno de los edificios del antiguo centro de salud de Bhimphedi.<\/figcaption><\/figure>\n<figure id=\"attachment_2151-3\" aria-describedby=\"caption-attachment-2151-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010681.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2151 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010681.jpg\" alt=\"p1010681\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010681.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010681-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2151-3\" class=\"wp-caption-text\">Otro de los edificios del antiguo centro de salud de Bhimphedi.<\/figcaption><\/figure>\n<figure id=\"attachment_2152-3\" aria-describedby=\"caption-attachment-2152-3\" style=\"width: 474px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010688.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2152 size-large\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010688-1024x172.jpg\" alt=\"p1010688\" width=\"474\" height=\"80\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010688-1024x172.jpg 1024w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010688-300x50.jpg 300w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010688-768x129.jpg 768w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><figcaption id=\"caption-attachment-2152-3\" class=\"wp-caption-text\">Recinto con los edificios hist\u00f3ricos del centro de salud. Al lado de estos edificios es d\u00f3nde se encuentran los nuevos edificios del actual centro de salud de la regi\u00f3n.<\/figcaption><\/figure>\n<figure id=\"attachment_2144-3\" aria-describedby=\"caption-attachment-2144-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010652.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2144 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010652.jpg\" alt=\"p1010652\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010652.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010652-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2144-3\" class=\"wp-caption-text\">Hatisar, las cuadras de los elefantes.<\/figcaption><\/figure>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010655.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2145\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010655.jpg\" alt=\"p1010655\" width=\"474\" height=\"356\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010655.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010655-300x225.jpg 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<figure id=\"attachment_2154-3\" aria-describedby=\"caption-attachment-2154-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2154 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/WhatsApp-Image-2016-12-02-at-18.35.45.jpeg\" alt=\"whatsapp-image-2016-12-02-at-18-35-45\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/WhatsApp-Image-2016-12-02-at-18.35.45.jpeg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/WhatsApp-Image-2016-12-02-at-18.35.45-300x225.jpeg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-2154-3\" class=\"wp-caption-text\">Una silla para elefante (con una copia del escudo brit\u00e1nico para honrar la visita de uno de los ministros brit\u00e1nicos a Bhimphedi).<\/figcaption><\/figure>\n<figure id=\"attachment_2146-3\" aria-describedby=\"caption-attachment-2146-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010664.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2146 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010664.jpg\" alt=\"p1010664\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010664.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010664-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2146-3\" class=\"wp-caption-text\">Edificio Janajati Hall, actualmente hotel de entidades (incluyendo la oficina de Awasuka), antiguamente residencia temporal del primer ministro ingl\u00e9s en su visita a Bhimphedi.<\/figcaption><\/figure>\n<figure id=\"attachment_2143-3\" aria-describedby=\"caption-attachment-2143-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/police.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2143 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/police.jpg\" alt=\"police\" width=\"600\" height=\"598\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/police.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/police-150x150.jpg 150w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/police-300x300.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2143-3\" class=\"wp-caption-text\">Edificio de la polic\u00eda de Bhimphedi.<\/figcaption><\/figure>\n<figure id=\"attachment_2153-3\" aria-describedby=\"caption-attachment-2153-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010689.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2153 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010689.jpg\" alt=\"p1010689\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010689.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010689-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2153-3\" class=\"wp-caption-text\">Mansi\u00f3n de una familia rica de aquellos tiempos. Edificio posteriormente adquirido por el Banco Nacional de Nepal, y actualmente en uso solo por alguna familia local como residencia.<\/figcaption><\/figure>\n<p>Preguntando a Surendra, uno de los personajes conocedores de la historia de Bhimphedi, nos explica que el edificio de la escuela fue en su origen un albergue de viajeros, cuando el pueblo era un importante punto de paso en la ruta hacia Chitwan y la India. M\u00e1s tarde se transform\u00f3 en escuela p\u00fablica y ha estado en uso hasta el pasado viernes 18 de noviembre de 2016. El pasado sabado ya se vaci\u00f3\u00a0todo el mobiliario para derribarlo pronto. Se\u00a0ha decidido derribar debido a los peque\u00f1os desperfectos que sufri\u00f3 durante el terremoto del a\u00f1o pasado. Los arquitectos que hemos pasado por Bhimphedi durante el \u00faltimo a\u00f1o, participantes del programa Awasuka, nos entristece la opini\u00f3n del gobierno, ya que creemos que el edificio es f\u00e1cilmente reparable y reforzable. Pero el gobierno nepal\u00ed aboga m\u00e1s por la reconstrucci\u00f3n completa que por hacer reparaciones y refuerzos a estos edificios hist\u00f3ricos&#8230; una verdadera l\u00e1stima! Aqu\u00ed os dejamos con algunas fotos del edificio, que pronto pasar\u00e1 a la historia.<\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2118\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-1.jpg\" alt=\"escola-1\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-1.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-1-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<figure id=\"attachment_2119-3\" aria-describedby=\"caption-attachment-2119-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2119 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-2.jpg\" alt=\"escola-2\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-2.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-2-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-2119-3\" class=\"wp-caption-text\">L&#8217;edifici va esdevenir escola l&#8217;any 1947 (2004 BS = Bikram Sambat Calendar, el calendari nepal\u00e8s).<\/figcaption><\/figure>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2117\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola-1024x678.jpg\" alt=\"portada-escola\" width=\"474\" height=\"314\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola-1024x678.jpg 1024w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola-300x199.jpg 300w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola-768x508.jpg 768w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/portada-escola.jpg 1500w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2115\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-8.jpg\" alt=\"escola-8\" width=\"600\" height=\"905\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-8.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-8-199x300.jpg 199w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2114\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-7.jpg\" alt=\"escola-7\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-7.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-7-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2122\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-5.jpg\" alt=\"escola-5\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-5.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-5-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2121\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-4.jpg\" alt=\"escola-4\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-4.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-4-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2120\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-3.jpg\" alt=\"escola-3\" width=\"600\" height=\"905\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-3.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-3-199x300.jpg 199w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2123\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-6.jpg\" alt=\"escola-6\" width=\"600\" height=\"397\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-6.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/escola-6-300x199.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<figure id=\"attachment_2131-3\" aria-describedby=\"caption-attachment-2131-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20160524_114536.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2131 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20160524_114536.jpg\" alt=\"20160524_114536\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20160524_114536.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20160524_114536-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2131-3\" class=\"wp-caption-text\">Hace unos meses, cuando se estaba construiendo la escuela provisional entre la prisi\u00f3n y el campo de futbol.<\/figcaption><\/figure>\n<figure id=\"attachment_2134-3\" aria-describedby=\"caption-attachment-2134-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20161124_144435.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2134 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20161124_144435.jpg\" alt=\"20161124_144435\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20161124_144435.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/20161124_144435-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2134-3\" class=\"wp-caption-text\">Des de esta semana las clases ya se hacen en la escuela provisional. Dicen que en dos a\u00f1os el nuevo edificio ya estar\u00e1 listo&#8230; Pero en cualquier caso, nadie parece triste de estar en este nuevo sitio, con un terreno tan grande para jugar.<\/figcaption><\/figure>\n<figure id=\"attachment_2147-3\" aria-describedby=\"caption-attachment-2147-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2147 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010671.jpg\" alt=\"p1010671\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010671.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010671-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-2147-3\" class=\"wp-caption-text\">Escombros de uno de los edificios hist\u00f3ricos ya derruidos. Al fondo se puede ver el antiguo edificio de la escuela. Una ni\u00f1a corre hacia all\u00ed, vestida de uniforme, para acudir a la fiesta de despedida del edificio.<\/figcaption><\/figure>\n<figure id=\"attachment_2148-3\" aria-describedby=\"caption-attachment-2148-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010673.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2148 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010673.jpg\" alt=\"p1010673\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010673.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010673-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2148-3\" class=\"wp-caption-text\">Foto del edificio y de la carpa con la fiesta de despedida del edificio.<\/figcaption><\/figure>\n<figure id=\"attachment_2149-3\" aria-describedby=\"caption-attachment-2149-3\" style=\"width: 600px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010676.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2149 size-full\" src=\"http:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010676.jpg\" alt=\"p1010676\" width=\"600\" height=\"450\" srcset=\"https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010676.jpg 600w, https:\/\/amicsnepal.blog.pangea.org\/files\/2016\/11\/P1010676-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-2149-3\" class=\"wp-caption-text\">Fiesta de despedida\/homenage al edificio Rana que usaba la escuela p\u00fablica de Bhimphedi.<\/figcaption><\/figure>\n<\/div>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Escrito por M\u00f2nica Sans, co-responsable de la casa de acogida de Bhimphedi y co-coordinadora de AWASUKA La dinast\u00eda Rana gobern\u00f3 Nepal desde 1846 hasta 1951, reduciendo a la monarqu\u00eda a una mera figura y haciendo que los cargos de Primer Ministro fueran hereditarios. El gobierno Rana se caracteriz\u00f3 por ser una tiran\u00eda con excesos, explotaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2539,"featured_media":2117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/users\/2539"}],"replies":[{"embeddable":true,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/comments?post=2071"}],"version-history":[{"count":15,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2071\/revisions"}],"predecessor-version":[{"id":2173,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/posts\/2071\/revisions\/2173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/media\/2117"}],"wp:attachment":[{"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/media?parent=2071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/categories?post=2071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amicsnepal.blog.pangea.org\/es\/wp-json\/wp\/v2\/tags?post=2071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}